{"id":14561,"date":"2014-03-03T00:00:00","date_gmt":"2014-03-02T21:00:00","guid":{"rendered":"https:\/\/uoninevah.edu.iq\/coee\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/"},"modified":"2014-03-03T00:00:00","modified_gmt":"2014-03-02T21:00:00","slug":"the-number-of-visitors-of-the-site-has-exceeded-50000","status":"publish","type":"post","link":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/","title":{"rendered":"The number of visitors of the site has exceeded 50000"},"content":{"rendered":"<p> &nbsp;<\/p>\n<div dir=\"rtl\" style=\"color: rgb(0, 0, 0); font-family: tahoma;\"> &nbsp;<\/div>\n<table border=\"0\" id=\"table1\" style=\"color: rgb(0, 0, 0); font-family: tahoma;\" width=\"100%\">\n<tbody>\n<tr>\n<td align=\"right\">\n<div align=\"center\" style=\"float: left;\">\n<div> <img decoding=\"async\" src=\"http:\/\/electronicengineering.uomosul.edu.iq\/files\/news\/news_2992454.jpg\" width=\"250px\" \/><\/div>\n<div> 2014-03-02 15:03:00<\/div>\n<\/p><\/div>\n<p> <span style=\"font-size: 16px;\">&nbsp;The number of visitors of the site has exceeded 50000<\/span><\/p>\n<p> <span style=\"font-size: 16px;\">The last two months have &nbsp;witnesed more than 4000 visitors<\/span><\/p>\n<p> <span style=\"font-size: 16px;\">about 86% of the visitors have voted (Very good) to the site, <\/span><\/p>\n<p> <span style=\"font-size: 16px;\">(while 5% have voted ( good , &nbsp;<\/span><\/p>\n<p> <span style=\"font-size: 16px;\">(but only 2.42% have voted (acceptable,<\/span><\/p>\n<div> &nbsp;<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The number of visitors of the site has exceeded 50000<\/p>\n","protected":false},"author":1,"featured_media":7723,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[33],"class_list":["post-14561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1","tag-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The number of visitors of the site has exceeded 50000 - \u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The number of visitors of the site has exceeded 50000\" \/>\n<meta property=\"og:description\" content=\"The number of visitors of the site has exceeded 50000\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-02T21:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2020\/11\/oldUo_20180707_103653_62.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#\\\/schema\\\/person\\\/41900b2174747e514f15e060fff06e0e\"},\"headline\":\"The number of visitors of the site has exceeded 50000\",\"datePublished\":\"2014-03-02T21:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/\"},\"wordCount\":56,\"publisher\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/oldUo_20180707_103653_62.png\",\"keywords\":[\"News\"],\"articleSection\":[\"\u0627\u0644\u0646\u0634\u0627\u0637\u0627\u062a\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/\",\"url\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/\",\"name\":\"The number of visitors of the site has exceeded 50000 - \u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/oldUo_20180707_103653_62.png\",\"datePublished\":\"2014-03-02T21:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/oldUo_20180707_103653_62.png\",\"contentUrl\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/oldUo_20180707_103653_62.png\",\"width\":400,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/en\\\/2014\\\/03\\\/03\\\/the-number-of-visitors-of-the-site-has-exceeded-50000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The number of visitors of the site has exceeded 50000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#website\",\"url\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/\",\"name\":\"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a\",\"description\":\"\u062c\u0627\u0645\u0639\u0629 \u0646\u064a\u0646\u0648\u0649\",\"publisher\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#organization\",\"name\":\"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a\",\"url\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/\u0634\u0639\u0627\u0631_\u062c\u0627\u0645\u0639\u0629_\u0646\u064a\u0646\u0648\u0649.png\",\"contentUrl\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/\u0634\u0639\u0627\u0631_\u062c\u0627\u0645\u0639\u0629_\u0646\u064a\u0646\u0648\u0649.png\",\"width\":400,\"height\":368,\"caption\":\"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a\"},\"image\":{\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/#\\\/schema\\\/person\\\/41900b2174747e514f15e060fff06e0e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f3cf09aae8a2e1adb8adb7a14d0c5f142d316b0a4a300707665e7a97b283c17?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f3cf09aae8a2e1adb8adb7a14d0c5f142d316b0a4a300707665e7a97b283c17?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f3cf09aae8a2e1adb8adb7a14d0c5f142d316b0a4a300707665e7a97b283c17?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/uoninevah.edu.iq\"],\"url\":\"https:\\\/\\\/uoninevah.edu.iq\\\/ee\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The number of visitors of the site has exceeded 50000 - \u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/","og_locale":"ar_AR","og_type":"article","og_title":"The number of visitors of the site has exceeded 50000","og_description":"The number of visitors of the site has exceeded 50000","og_url":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/","og_site_name":"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a","article_published_time":"2014-03-02T21:00:00+00:00","og_image":[{"width":400,"height":565,"url":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2020\/11\/oldUo_20180707_103653_62.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#article","isPartOf":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/"},"author":{"name":"admin","@id":"https:\/\/uoninevah.edu.iq\/ee\/#\/schema\/person\/41900b2174747e514f15e060fff06e0e"},"headline":"The number of visitors of the site has exceeded 50000","datePublished":"2014-03-02T21:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/"},"wordCount":56,"publisher":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/#organization"},"image":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#primaryimage"},"thumbnailUrl":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2020\/11\/oldUo_20180707_103653_62.png","keywords":["News"],"articleSection":["\u0627\u0644\u0646\u0634\u0627\u0637\u0627\u062a"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/","url":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/","name":"The number of visitors of the site has exceeded 50000 - \u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a","isPartOf":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#primaryimage"},"image":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#primaryimage"},"thumbnailUrl":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2020\/11\/oldUo_20180707_103653_62.png","datePublished":"2014-03-02T21:00:00+00:00","breadcrumb":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#primaryimage","url":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2020\/11\/oldUo_20180707_103653_62.png","contentUrl":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2020\/11\/oldUo_20180707_103653_62.png","width":400,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/uoninevah.edu.iq\/ee\/en\/2014\/03\/03\/the-number-of-visitors-of-the-site-has-exceeded-50000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/uoninevah.edu.iq\/ee\/"},{"@type":"ListItem","position":2,"name":"The number of visitors of the site has exceeded 50000"}]},{"@type":"WebSite","@id":"https:\/\/uoninevah.edu.iq\/ee\/#website","url":"https:\/\/uoninevah.edu.iq\/ee\/","name":"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a","description":"\u062c\u0627\u0645\u0639\u0629 \u0646\u064a\u0646\u0648\u0649","publisher":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uoninevah.edu.iq\/ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/uoninevah.edu.iq\/ee\/#organization","name":"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a","url":"https:\/\/uoninevah.edu.iq\/ee\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/uoninevah.edu.iq\/ee\/#\/schema\/logo\/image\/","url":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2024\/11\/\u0634\u0639\u0627\u0631_\u062c\u0627\u0645\u0639\u0629_\u0646\u064a\u0646\u0648\u0649.png","contentUrl":"https:\/\/uoninevah.edu.iq\/ee\/wp-content\/uploads\/sites\/3\/2024\/11\/\u0634\u0639\u0627\u0631_\u062c\u0627\u0645\u0639\u0629_\u0646\u064a\u0646\u0648\u0649.png","width":400,"height":368,"caption":"\u0643\u0644\u064a\u0629 \u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a"},"image":{"@id":"https:\/\/uoninevah.edu.iq\/ee\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uoninevah.edu.iq\/ee\/#\/schema\/person\/41900b2174747e514f15e060fff06e0e","name":"admin","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/2f3cf09aae8a2e1adb8adb7a14d0c5f142d316b0a4a300707665e7a97b283c17?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f3cf09aae8a2e1adb8adb7a14d0c5f142d316b0a4a300707665e7a97b283c17?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f3cf09aae8a2e1adb8adb7a14d0c5f142d316b0a4a300707665e7a97b283c17?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/uoninevah.edu.iq"],"url":"https:\/\/uoninevah.edu.iq\/ee\/author\/admin\/"}]}},"lang":"en","translations":{"en":14561},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/posts\/14561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/comments?post=14561"}],"version-history":[{"count":0,"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/posts\/14561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/media\/7723"}],"wp:attachment":[{"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/media?parent=14561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/categories?post=14561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uoninevah.edu.iq\/ee\/wp-json\/wp\/v2\/tags?post=14561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}